{"id":71485,"date":"2021-07-12T22:22:30","date_gmt":"2021-07-12T20:22:39","guid":{"rendered":"https:\/\/www.laperlavalles2.bcntic.com\/product\/locion-peinadora-hidratante-nina-con-aceite-de-oliva\/"},"modified":"2023-06-23T11:14:08","modified_gmt":"2023-06-23T09:14:08","slug":"locion-peinadora-hidratante-nina-con-aceite-de-oliva","status":"publish","type":"product","link":"https:\/\/www.laperlavalles.cat\/es\/product\/locion-peinadora-hidratante-nina-con-aceite-de-oliva\/","title":{"rendered":"OLIVE OIL GIRLS MOISTURIZING LOTION"},"content":{"rendered":"<p>Loci\u00f3n hidratante para el pelo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Loci\u00f3n hidratante para el pelo.<\/p>\n","protected":false},"featured_media":165736,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[8403],"product_tag":[],"_links":{"self":[{"href":"https:\/\/www.laperlavalles.cat\/es\/wp-json\/wp\/v2\/product\/71485"}],"collection":[{"href":"https:\/\/www.laperlavalles.cat\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.laperlavalles.cat\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laperlavalles.cat\/es\/wp-json\/wp\/v2\/comments?post=71485"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laperlavalles.cat\/es\/wp-json\/wp\/v2\/media\/165736"}],"wp:attachment":[{"href":"https:\/\/www.laperlavalles.cat\/es\/wp-json\/wp\/v2\/media?parent=71485"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.laperlavalles.cat\/es\/wp-json\/wp\/v2\/product_cat?post=71485"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.laperlavalles.cat\/es\/wp-json\/wp\/v2\/product_tag?post=71485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}